{"id":302,"date":"2018-08-14T15:20:24","date_gmt":"2018-08-14T13:20:24","guid":{"rendered":"https:\/\/magazine.zhermack.com\/sin-categorizar\/prevenire-le-infezioni-in-uno-studio-odontoiatrico-protocolli-standard-e-concetti-chiave\/"},"modified":"2025-05-08T11:28:37","modified_gmt":"2025-05-08T09:28:37","slug":"evitar-infecciones-en-una-consulta-dental-protocolos-estandar-y-conceptos-clave","status":"publish","type":"post","link":"https:\/\/magazine.zhermack.com\/es\/higiene-es\/evitar-infecciones-en-una-consulta-dental-protocolos-estandar-y-conceptos-clave\/","title":{"rendered":"Evitar infecciones en una consulta dental: protocolos est\u00e1ndar y conceptos clave"},"content":{"rendered":"<p>Para garantizar la higiene dentro de unas instalaciones odontol\u00f3gicas, es necesario formar debidamente al personal de la consulta y elegir metodolog\u00edas e instrumentos eficaces que permitan garantizar un elevado grado de protecci\u00f3n.<\/p>\n<p><!--more--><\/p>\n<h2>La propagaci\u00f3n de infecciones en el estudio<\/h2>\n<p>Las infecciones pueden deberse a <strong>virus<\/strong>, <strong>bacterias<\/strong> y <strong>esporas<\/strong>. Todos los procedimientos que se llevan a cabo en un espacio de trabajo odontol\u00f3gico usando elementos manuales generan un aerosol, que a su vez act\u00faa como veh\u00edculo (sutil e invisible) para la transmisi\u00f3n de pat\u00f3genos y residuos org\u00e1nicos en cualquier direcci\u00f3n. As\u00ed, las manos del personal, las \u00e1reas de trabajo y el campo operatorio son zonas con un alto nivel de exposici\u00f3n.<\/p>\n<p>En particular, un<strong> aerosol generado por una turbina<\/strong> dental provoca un aumento de la concentraci\u00f3n de microorganismos en el aire de en torno al 2.200 %. Un aerosol generado <strong>por una cureta ultras\u00f3nica<\/strong> provoca un aumento de la concentraci\u00f3n de microorganismos en el aire de en torno al 3.000 %. El aerosol permite a los microorganismos recircular y, como resultado, el ambiente puede permanecer en estado infeccioso durante largos periodos de tiempo.<\/p>\n<p>Todas las <strong>part\u00edculas<\/strong> de un di\u00e1metro comprendido entre 0,5 y 50 micras que se dejen expuestas al aire tras toses, estornudos y tratamientos quedar\u00e1n suspendidas en el aire durante al menos 24 horas y se considerar\u00e1n como aerosol. Pueden clasificarse tambi\u00e9n seg\u00fan su di\u00e1metro:<\/p>\n<ul>\n<li><strong>10-50 micras<\/strong>: si permanecen en la nariz y las v\u00edas respiratorias superiores<\/li>\n<li><strong>5-10 micras<\/strong>: pueden alcanzar la faringe y la tr\u00e1quea<\/li>\n<li><strong>0,5-5 micras<\/strong>: pueden llegar a los bronquiolos y a los alveolos pulmonares<\/li>\n<\/ul>\n<h3>Las piedras angulares de la prevenci\u00f3n<\/h3>\n<p>Debido a la elevada concentraci\u00f3n de fuentes de infecciones potenciales dentro de una consulta dental, constituye una buena norma respetar estos tres puntos clave:<\/p>\n<ol>\n<li>Tratar a cada paciente como una fuente de infecci\u00f3n en potencia, tanto por el bien del propio paciente como por el de los pacientes posteriores y el personal de la consulta. Hay que prestar particular atenci\u00f3n a la historia cl\u00ednica, pero no bajar tampoco la guardia en caso de anamnesis negativa;<\/li>\n<li>Utilizar todos los sistemas de protecci\u00f3n que procedan;<\/li>\n<li>Seguir protocolos precisos, estandarizados y repetibles para la descontaminaci\u00f3n y desinfecci\u00f3n de la consulta.<\/li>\n<\/ol>\n<p>Este \u00faltimo punto en particular depende de la elecci\u00f3n de un agente desinfectante adecuado para su uso dentro de la propia consulta.<\/p>\n<h3>C\u00f3mo elegir el desinfectante<\/h3>\n<p>Dicha elecci\u00f3n es una tarea delicada y fundamental para garantizar a los pacientes, al personal (cl\u00ednico, extracl\u00ednico o auxiliar) y al propio odont\u00f3logo la m\u00e1xima protecci\u00f3n contra el riego de infecciones cruzadas. El primer requisito para elegir correctamente es conocer la diferencia entre los tres conceptos siguientes:<\/p>\n<ul>\n<li><strong>Limpieza<\/strong> &#8211; eliminaci\u00f3n mec\u00e1nica de material org\u00e1nico del equipo dental y de las superficies;<\/li>\n<li><strong>Descontaminaci\u00f3n<\/strong> &#8211; proceso que permite eliminar (matar o desactivar) todos los microrganismos salvo las esporas;<\/li>\n<li><strong>Esterilizaci\u00f3n<\/strong> &#8211; proceso que elimina todos los microorganismos, incluidas las esporas.<\/li>\n<\/ul>\n<p>La misi\u00f3n de los productos de desinfecci\u00f3n es cumplimentar de manera eficaz las tareas de limpieza y descontaminaci\u00f3n (ver puntos 1 y 2).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para garantizar la higiene dentro de unas instalaciones odontol\u00f3gicas, es necesario formar debidamente al personal de la consulta y elegir metodolog\u00edas e instrumentos eficaces que permitan garantizar un elevado grado de protecci\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":415,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[47],"tags":[135,156,165],"class_list":["post-302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-higiene-es","tag-desinfeccion","tag-odontologia","tag-prevencion"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/posts\/302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/comments?post=302"}],"version-history":[{"count":1,"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/posts\/302\/revisions"}],"predecessor-version":[{"id":6013,"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/posts\/302\/revisions\/6013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/media\/415"}],"wp:attachment":[{"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/media?parent=302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/categories?post=302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magazine.zhermack.com\/es\/wp-json\/wp\/v2\/tags?post=302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}